{"id":12056,"count":1,"description":"","link":"https:\/\/savingtherepublic.com\/blog\/tag\/al-qaeda-releases-video-of-american-pleading-to-obama-my-life-is-in-your-hands\/","name":"Al Qaeda Releases Video of American Pleading to Obama 'My Life is in Your Hands","slug":"al-qaeda-releases-video-of-american-pleading-to-obama-my-life-is-in-your-hands","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/savingtherepublic.com\/blog\/wp-json\/wp\/v2\/tags\/12056"}],"collection":[{"href":"https:\/\/savingtherepublic.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/savingtherepublic.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/savingtherepublic.com\/blog\/wp-json\/wp\/v2\/posts?tags=12056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}