{"id":24245,"count":1,"description":"","link":"https:\/\/savingtherepublic.com\/blog\/tag\/obama-drone-protesters-force-feinstein-to-clear-brennan-hearing-room\/","name":"Obama Drone Protesters Force Feinstein To Clear Brennan Hearing Room","slug":"obama-drone-protesters-force-feinstein-to-clear-brennan-hearing-room","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/savingtherepublic.com\/blog\/wp-json\/wp\/v2\/tags\/24245"}],"collection":[{"href":"https:\/\/savingtherepublic.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/savingtherepublic.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/savingtherepublic.com\/blog\/wp-json\/wp\/v2\/posts?tags=24245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}