{"id":27822,"count":1,"description":"","link":"https:\/\/savingtherepublic.com\/blog\/tag\/greg-gutfeld-welcome-to-america-now-80-more-like-afghanistan\/","name":"Greg Gutfeld Welcome To America Now 80% More Like Afghanistan","slug":"greg-gutfeld-welcome-to-america-now-80-more-like-afghanistan","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/savingtherepublic.com\/blog\/wp-json\/wp\/v2\/tags\/27822"}],"collection":[{"href":"https:\/\/savingtherepublic.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/savingtherepublic.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/savingtherepublic.com\/blog\/wp-json\/wp\/v2\/posts?tags=27822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}